{"id":3432,"date":"2020-12-23T05:54:00","date_gmt":"2020-12-23T05:54:00","guid":{"rendered":"https:\/\/acgl-ito.eu\/AMSRB\/?page_id=3432"},"modified":"2023-06-01T11:44:44","modified_gmt":"2023-06-01T11:44:44","slug":"datenschutz","status":"publish","type":"page","link":"https:\/\/amsrb-nato.com\/de\/home\/datenschutz\/","title":{"rendered":"Datenschutz"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\"><style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id_1f6651-b5{margin-top:0px;margin-bottom:0px;}.kb-row-layout-id_1f6651-b5 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id_1f6651-b5 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id_1f6651-b5 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1170px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:10px;padding-right:10px;padding-bottom:56px;padding-left:10px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id_1f6651-b5{background-image:url('https:\/\/acgl-ito.eu\/AMSRB\/wp-content\/uploads\/cropped-AMSRB-Logo-WB-modified.png');background-size:auto 75%;background-position:50% 50%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id_1f6651-b5 > .kt-row-layout-overlay{opacity:0.00;background-color:var(--global-palette2, #2B6CB0);mix-blend-mode:normal;}@media all and (max-width: 1024px){.kb-row-layout-id_1f6651-b5 > .kt-row-column-wrap{padding-top:120px;padding-right:120px;padding-bottom:60px;padding-left:60px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id_1f6651-b5 > .kt-row-column-wrap{padding-right:20px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id_1f6651-b5 alignnone has-theme-palette1-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column_ff1bca-2e > .kt-inside-inner-col,.kadence-column_ff1bca-2e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_ff1bca-2e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_ff1bca-2e > .kt-inside-inner-col{flex-direction:column;}.kadence-column_ff1bca-2e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_ff1bca-2e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_ff1bca-2e{position:relative;}@media all and (max-width: 1024px){.kadence-column_ff1bca-2e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_ff1bca-2e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_ff1bca-2e inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading_fadf30-af, .wp-block-kadence-advancedheading.kt-adv-heading_fadf30-af[data-kb-block=\"kb-adv-heading_fadf30-af\"]{padding-top:var(--global-kb-spacing-sm, 1.5rem);margin-bottom:20px;text-align:left;font-size:30px;line-height:1em;font-style:normal;letter-spacing:-2px;color:#ffffff;text-shadow:3px 5px 2px rgba(0, 0, 0, 0.2);}.wp-block-kadence-advancedheading.kt-adv-heading_fadf30-af mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading_fadf30-af[data-kb-block=\"kb-adv-heading_fadf30-af\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading_fadf30-af img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading_fadf30-af[data-kb-block=\"kb-adv-heading_fadf30-af\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading_fadf30-af, .wp-block-kadence-advancedheading.kt-adv-heading_fadf30-af[data-kb-block=\"kb-adv-heading_fadf30-af\"]{text-shadow:3px 5px 2px rgba(0, 0, 0, 0.2);font-size:60px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading_fadf30-af, .wp-block-kadence-advancedheading.kt-adv-heading_fadf30-af[data-kb-block=\"kb-adv-heading_fadf30-af\"]{text-shadow:3px 5px 2px rgba(0, 0, 0, 0.2);font-size:45px;}}<\/style>\n<h1 class=\"kt-adv-heading_fadf30-af wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading_fadf30-af\">AMSRB-NATO Club<\/h1>\n\n\n\n<p class=\"has-theme-palette-9-color has-text-color\">Valley of Washington, D.C.<\/p>\n<\/div><\/div>\n\n<\/div><\/div><\/div>\n<\/div>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id_93ff07-76{margin-top:-55px;margin-bottom:0px;}.kb-row-layout-id_93ff07-76 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id_93ff07-76 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id_93ff07-76 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1140px;margin-left:auto;margin-right:auto;padding-top:10px;padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id_93ff07-76 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id_93ff07-76 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id_93ff07-76 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id_93ff07-76 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column_e696f5-74 > .kt-inside-inner-col{padding-top:40px;padding-right:30px;padding-bottom:10px;padding-left:30px;}.kadence-column_e696f5-74 > .kt-inside-inner-col,.kadence-column_e696f5-74 > .kt-inside-inner-col:before{border-top-left-radius:6px;border-top-right-radius:6px;border-bottom-right-radius:6px;border-bottom-left-radius:6px;}.kadence-column_e696f5-74 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_e696f5-74 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_e696f5-74 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_e696f5-74 > .kt-inside-inner-col{background-color:var(--global-palette8, #F7FAFC);}.kadence-column_e696f5-74 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_e696f5-74{position:relative;}@media all and (max-width: 1024px){.kadence-column_e696f5-74 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_e696f5-74 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_e696f5-74 inner-column-1\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-text-align-center has-14-null-null-font-size\">Datenschutzinformationen<\/h2>\n\n\n<style>.kadence-column_fe0175-29 > .kt-inside-inner-col{padding-top:40px;padding-right:30px;padding-bottom:10px;padding-left:30px;}.kadence-column_fe0175-29 > .kt-inside-inner-col,.kadence-column_fe0175-29 > .kt-inside-inner-col:before{border-top-left-radius:6px;border-top-right-radius:6px;border-bottom-right-radius:6px;border-bottom-left-radius:6px;}.kadence-column_fe0175-29 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_fe0175-29 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_fe0175-29 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_fe0175-29 > .kt-inside-inner-col{background-color:var(--global-palette8, #F7FAFC);}.kadence-column_fe0175-29 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_fe0175-29{position:relative;}@media all and (max-width: 1024px){.kadence-column_fe0175-29 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_fe0175-29 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_fe0175-29 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-_f01527-be .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-_f01527-be .kt-divider{border-top-width:1px;height:1px;border-top-color:var(--global-palette6, #718096);width:99%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-_f01527-be\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">1. Datenschutz auf einen Blick<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Allgemeine Hinweise<\/h3>\n\n\n\n<p>Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie diese Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Datenerfassung auf dieser Website<\/h3>\n\n\n\n<p><strong>Wer ist verantwortlich f\u00fcr die Datenerfassung auf dieser Website?<\/strong><\/p>\n\n\n\n<p>Die Datenverarbeitung auf dieser Website erfolgt durch den Websitebetreiber. Dessen Kontaktdaten k\u00f6nnen Sie dem <a href=\"https:\/\/acgl-ito.eu\/AMSRB\/impressum\/\">Impressum<\/a> dieser Website entnehmen.<\/p>\n\n\n\n<p><strong>Wie erfassen wir Ihre Daten?<\/strong><\/p>\n\n\n\n<p>Ihre Daten werden zum einen dadurch erhoben, dass Sie uns diese mitteilen. Hierbei kann es sich z.&nbsp;B. um Daten handeln, die Sie in ein Kontaktformular eingeben.<\/p>\n\n\n\n<p>Andere Daten werden automatisch oder nach Ihrer Einwilligung beim Besuch der Website durch unsere IT-Systeme erfasst. Das sind vor allem technische Daten (z.&nbsp;B. Internetbrowser, Betriebssystem oder Uhrzeit des Seitenaufrufs). Die Erfassung dieser Daten erfolgt automatisch, sobald Sie diese Website betreten.<\/p>\n\n\n\n<p><strong>Wof\u00fcr nutzen wir Ihre Daten?<\/strong><\/p>\n\n\n\n<p>Ein Teil der Daten wird erhoben, um eine fehlerfreie Bereitstellung der Website zu gew\u00e4hrleisten. Andere Daten k\u00f6nnen zur Analyse Ihres Nutzerverhaltens verwendet werden.<\/p>\n\n\n\n<p><strong>Welche Rechte haben Sie bez\u00fcglich Ihrer Daten?<\/strong><\/p>\n\n\n\n<p>Sie haben jederzeit das Recht, unentgeltlich Auskunft \u00fcber Herkunft, Empf\u00e4nger und Zweck Ihrer gespeicherten personenbezogenen Daten zu erhalten. Sie haben au\u00dferdem ein Recht, die Berichtigung oder L\u00f6schung dieser Daten zu verlangen. Wenn Sie eine Einwilligung zur Datenverarbeitung erteilt haben, k\u00f6nnen Sie diese Einwilligung jederzeit f\u00fcr die Zukunft widerrufen. Au\u00dferdem haben Sie das Recht, unter bestimmten Umst\u00e4nden die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen. Des Weiteren steht Ihnen ein Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde zu.<\/p>\n\n\n\n<p>Hierzu sowie zu weiteren Fragen zum Thema Datenschutz k\u00f6nnen Sie sich jederzeit unter der im Impressum angegebenen Adresse an uns wenden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Analyse-Tools und Tools von Drittanbietern<\/h3>\n\n\n\n<p>Beim Besuch dieser Website kann Ihr Surf-Verhalten statistisch ausgewertet werden. Das geschieht vor allem mit Cookies und mit sogenannten Analyseprogrammen.<\/p>\n\n\n\n<p>Detaillierte Informationen zu diesen Analyseprogrammen finden Sie in der folgenden Datenschutzerkl\u00e4rung.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">2. Hosting und Content Delivery Networks (CDN)<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Externes Hosting<\/h3>\n\n\n\n<p>Diese Website wird bei einem externen Dienstleister gehostet (Hoster). Die personenbezogenen Daten, die auf dieser Website erfasst werden, werden auf den Servern des Hosters gespeichert. Hierbei kann es sich v. a. um IP-Adressen, Kontaktanfragen, Meta- und Kommunikationsdaten, Vertragsdaten, Kontaktdaten, Namen, Webseitenzugriffe und sonstige Daten, die \u00fcber eine Website generiert werden, handeln.<\/p>\n\n\n\n<p>Der Einsatz des Hosters erfolgt zum Zwecke der Vertragserf\u00fcllung gegen\u00fcber unseren potenziellen und bestehenden Kunden (Art. 6 Abs. 1 lit. b DSGVO) und im Interesse einer sicheren, schnellen und effizienten Bereitstellung unseres Online-Angebots durch einen professionellen Anbieter (Art. 6 Abs. 1 lit. f DSGVO).<\/p>\n\n\n\n<p>Unser Hoster wird Ihre Daten nur insoweit verarbeiten, wie dies zur Erf\u00fcllung seiner Leistungspflichten erforderlich ist und unsere Weisungen in Bezug auf diese Daten befolgen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">3. Allgemeine Hinweise und Pflichtinformationen<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Datenschutz<\/h3>\n\n\n\n<p>Die Betreiber dieser Seiten nehmen den Schutz Ihrer pers\u00f6nlichen Daten sehr ernst. Wir behandeln Ihre personenbezogenen Daten vertraulich und entsprechend der gesetzlichen Datenschutzvorschriften sowie dieser Datenschutzerkl\u00e4rung.<\/p>\n\n\n\n<p>Wenn Sie diese Website benutzen, werden verschiedene personenbezogene Daten erhoben. Personenbezogene Daten sind Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Die vorliegende Datenschutzerkl\u00e4rung erl\u00e4utert, welche Daten wir erheben und wof\u00fcr wir sie nutzen. Sie erl\u00e4utert auch, wie und zu welchem Zweck das geschieht.<\/p>\n\n\n\n<p>Wir weisen darauf hin, dass die Daten\u00fcbertragung im Internet (z.&nbsp;B. bei der Kommunikation per E-Mail) Sicherheitsl\u00fccken aufweisen kann. Ein l\u00fcckenloser Schutz der Daten vor dem Zugriff durch Dritte ist nicht m\u00f6glich.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Hinweis zur verantwortlichen Stelle<\/h3>\n\n\n\n<p>Die verantwortliche Stelle f\u00fcr die Datenverarbeitung auf dieser Website ist:<\/p>\n\n\n\n<p>AMSRB-NATO Club<br>Hindenburgstr. 30, <br>97469 Gochsheim, Germany<\/p>\n\n\n\n<p><strong>Vertreten durch<\/strong>:<\/p>\n\n\n\n<p>1. Vorsitzender<br>Schriftf\u00fchrer<\/p>\n\n\n\n<p><strong>Kontakt:<\/strong><\/p>\n\n\n\n<p>E-MAIL:&nbsp;<a href=\"mailto:communications@amsrb-nato.com\" target=\"_blank\" aria-label=\"communications@amsrb-nato.com (opens in a new tab)\" rel=\"noreferrer noopener\" class=\"ek-link\">communications@amsrb-nato.com<\/a><\/p>\n\n\n\n<p>Verantwortliche Stelle ist die nat\u00fcrliche oder juristische Person, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung von personenbezogenen Daten (z.&nbsp;B. Namen, E-Mail-Adressen o. \u00c4.) entscheidet.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Widerruf Ihrer Einwilligung zur Datenverarbeitung<\/h3>\n\n\n\n<p>Viele Datenverarbeitungsvorg\u00e4nge sind nur mit Ihrer ausdr\u00fccklichen Einwilligung m\u00f6glich. Sie k\u00f6nnen eine bereits erteilte Einwilligung jederzeit widerrufen. Dazu reicht eine formlose Mitteilung per E-Mail an uns. Die Rechtm\u00e4\u00dfigkeit der bis zum Widerruf erfolgten Datenverarbeitung bleibt vom Widerruf unber\u00fchrt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Widerspruchsrecht gegen die Datenerhebung in besonderen F\u00e4llen sowie gegen Direktwerbung (Art. 21 DSGVO)<\/h3>\n\n\n\n<p>WENN DIE DATENVERARBEITUNG AUF GRUNDLAGE VON ART. 6 ABS. 1 LIT. E ODER F DSGVO ERFOLGT, HABEN SIE JEDERZEIT DAS RECHT, AUS GR\u00dcNDEN, DIE SICH AUS IHRER BESONDEREN SITUATION ERGEBEN, GEGEN DIE VERARBEITUNG IHRER PERSONENBEZOGENEN DATEN WIDERSPRUCH EINZULEGEN; DIES GILT AUCH F\u00dcR EIN AUF DIESE BESTIMMUNGEN GEST\u00dcTZTES PROFILING. DIE JEWEILIGE RECHTSGRUNDLAGE, AUF DENEN EINE VERARBEITUNG BERUHT, ENTNEHMEN SIE DIESER DATENSCHUTZERKL\u00c4RUNG. WENN SIE WIDERSPRUCH EINLEGEN, WERDEN WIR IHRE BETROFFENEN PERSONENBEZOGENEN DATEN NICHT MEHR VERARBEITEN, ES SEI DENN, WIR K\u00d6NNEN ZWINGENDE SCHUTZW\u00dcRDIGE GR\u00dcNDE F\u00dcR DIE VERARBEITUNG NACHWEISEN, DIE IHRE INTERESSEN, RECHTE UND FREIHEITEN \u00dcBERWIEGEN ODER DIE VERARBEITUNG DIENT DER GELTENDMACHUNG, AUS\u00dcBUNG ODER VERTEIDIGUNG VON RECHTSANSPR\u00dcCHEN (WIDERSPRUCH NACH ART. 21 ABS. 1 DSGVO).<\/p>\n\n\n\n<p>WERDEN IHRE PERSONENBEZOGENEN DATEN VERARBEITET, UM DIREKTWERBUNG ZU BETREIBEN, SO HABEN SIE DAS RECHT, JEDERZEIT WIDERSPRUCH GEGEN DIE VERARBEITUNG SIE BETREFFENDER PERSONENBEZOGENER DATEN ZUM ZWECKE DERARTIGER WERBUNG EINZULEGEN; DIES GILT AUCH F\u00dcR DAS PROFILING, SOWEIT ES MIT SOLCHER DIREKTWERBUNG IN VERBINDUNG STEHT. WENN SIE WIDERSPRECHEN, WERDEN IHRE PERSONENBEZOGENEN DATEN ANSCHLIESSEND NICHT MEHR ZUM ZWECKE DER DIREKTWERBUNG VERWENDET (WIDERSPRUCH NACH ART. 21 ABS. 2 DSGVO).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde<\/h3>\n\n\n\n<p>Im Falle von Verst\u00f6\u00dfen gegen die DSGVO steht den Betroffenen ein Beschwerderecht bei einer Aufsichtsbeh\u00f6rde, insbesondere in dem Mitgliedstaat ihres gew\u00f6hnlichen Aufenthalts, ihres Arbeitsplatzes oder des Orts des mutma\u00dflichen Versto\u00dfes zu. Das Beschwerderecht besteht unbeschadet anderweitiger verwaltungsrechtlicher oder gerichtlicher Rechtsbehelfe.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Recht auf Daten\u00fcbertragbarkeit<\/h3>\n\n\n\n<p>Sie haben das Recht, Daten, die wir auf Grundlage Ihrer Einwilligung oder in Erf\u00fcllung eines Vertrags automatisiert verarbeiten, an sich oder an einen Dritten in einem g\u00e4ngigen, maschinenlesbaren Format aush\u00e4ndigen zu lassen. Sofern Sie die direkte \u00dcbertragung der Daten an einen anderen Verantwortlichen verlangen, erfolgt dies nur, soweit es technisch machbar ist.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Auskunft, L\u00f6schung und Berichtigung<\/h3>\n\n\n\n<p>Sie haben im Rahmen der geltenden gesetzlichen Bestimmungen jederzeit das Recht auf unentgeltliche Auskunft \u00fcber Ihre gespeicherten personenbezogenen Daten, deren Herkunft und Empf\u00e4nger und den Zweck der Datenverarbeitung und ggf. ein Recht auf Berichtigung oder L\u00f6schung dieser Daten. Hierzu sowie zu weiteren Fragen zum Thema personenbezogene Daten k\u00f6nnen Sie sich jederzeit unter der im Impressum angegebenen Adresse an uns wenden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Recht auf Einschr\u00e4nkung der Verarbeitung<\/h3>\n\n\n\n<p>Sie haben das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen. Hierzu k\u00f6nnen Sie sich jederzeit unter der im Impressum angegebenen Adresse an uns wenden. Das Recht auf Einschr\u00e4nkung der Verarbeitung besteht in folgenden F\u00e4llen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Wenn Sie die Richtigkeit Ihrer bei uns gespeicherten personenbezogenen Daten bestreiten, ben\u00f6tigen wir in der Regel Zeit, um dies zu \u00fcberpr\u00fcfen. F\u00fcr die Dauer der Pr\u00fcfung haben Sie das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/li>\n\n\n\n<li>Wenn die Verarbeitung Ihrer personenbezogenen Daten unrechtm\u00e4\u00dfig geschah\/geschieht, k\u00f6nnen Sie statt der L\u00f6schung die Einschr\u00e4nkung der Datenverarbeitung verlangen.<\/li>\n\n\n\n<li>Wenn wir Ihre personenbezogenen Daten nicht mehr ben\u00f6tigen, Sie sie jedoch zur Aus\u00fcbung, Verteidigung oder Geltendmachung von Rechtsanspr\u00fcchen ben\u00f6tigen, haben Sie das Recht, statt der L\u00f6schung die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/li>\n\n\n\n<li>Wenn Sie einen Widerspruch nach Art. 21 Abs. 1 DSGVO eingelegt haben, muss eine Abw\u00e4gung zwischen Ihren und unseren Interessen vorgenommen werden. Solange noch nicht feststeht, wessen Interessen \u00fcberwiegen, haben Sie das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/li>\n<\/ul>\n\n\n\n<p>Wenn Sie die Verarbeitung Ihrer personenbezogenen Daten eingeschr\u00e4nkt haben, d\u00fcrfen diese Daten \u2013 von ihrer Speicherung abgesehen \u2013 nur mit Ihrer Einwilligung oder zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen oder zum Schutz der Rechte einer anderen nat\u00fcrlichen oder juristischen Person oder aus Gr\u00fcnden eines wichtigen \u00f6ffentlichen Interesses der Europ\u00e4ischen Union oder eines Mitgliedstaats verarbeitet werden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">4. Datenerfassung auf dieser Website<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Registrierung auf unserer Website<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Art und Zweck der Verarbeitung:<\/h3>\n\n\n\n<p>Bei der Registrierung f\u00fcr die Nutzung unserer personalisierten Leistungen werden einige personenbezogene Daten erhoben, wie Name, Anschrift, Kontakt- und Kommunikationsdaten (z. B. Telefonnummer und E-Mail-Adresse). Sind Sie bei uns registriert, k\u00f6nnen Sie auf Inhalte und Leistungen zugreifen, die wir nur registrierten Nutzern anbieten. Angemeldete Nutzer haben zudem die M\u00f6glichkeit, bei Bedarf die bei Registrierung angegebenen Daten jederzeit zu \u00e4ndern oder zu l\u00f6schen. Selbstverst\u00e4ndlich erteilen wir Ihnen dar\u00fcber hinaus jederzeit Auskunft \u00fcber die von uns \u00fcber Sie gespeicherten personenbezogenen Daten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Rechtsgrundlage:<\/h3>\n\n\n\n<p>Die Verarbeitung der bei der Registrierung eingegebenen Daten erfolgt auf Grundlage einer Einwilligung des Nutzers (Art. 6 Abs. 1 lit. a DSGVO).<\/p>\n\n\n\n<p>Dient die Registrierung der Erf\u00fcllung eines Vertrages, dessen Vertragspartei die betroffene Person ist oder der Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen, so ist zus\u00e4tzliche Rechtsgrundlage f\u00fcr die Verarbeitung der Daten Art. 6 Abs. 1 lit. b DSGVO.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Empf\u00e4nger:<\/h3>\n\n\n\n<p>Empf\u00e4nger der Daten sind ggf. technische Dienstleister, die f\u00fcr den Betrieb und die Wartung unserer Website als Auftragsverarbeiter t\u00e4tig werden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Speicherdauer:<\/h3>\n\n\n\n<p>Daten werden in diesem Zusammenhang nur verarbeitet, solange die entsprechende Einwilligung vorliegt. Danach werden sie gel\u00f6scht, soweit keine gesetzlichen Aufbewahrungspflichten entgegenstehen. Zur Kontaktaufnahme in diesem Zusammenhang nutzen Sie bitte die am Ende dieser Datenschutzerkl\u00e4rung angegebenen Kontaktdaten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Bereitstellung vorgeschrieben oder erforderlich:<\/h3>\n\n\n\n<p>Die Bereitstellung Ihrer personenbezogenen Daten erfolgt freiwillig, allein auf Basis Ihrer Einwilligung. Ohne die Bereitstellung Ihrer personenbezogenen Daten k\u00f6nnen wir Ihnen keinen Zugang auf unsere angebotenen Inhalte und Leistungen gew\u00e4hren.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Erbringung kostenpflichtiger Leistungen<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Art und Zweck der Verarbeitung:<\/h3>\n\n\n\n<p>Zur Erbringung kostenpflichtiger Leistungen werden von uns zus\u00e4tzliche Daten erfragt, wie z.B. Zahlungsangaben, um Ihre Bestellung ausf\u00fchren zu k\u00f6nnen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Rechtsgrundlage:<\/h3>\n\n\n\n<p>Die Verarbeitung der Daten, die f\u00fcr den Abschluss des Vertrages erforderlich ist, basiert auf Art. 6 Abs. 1 lit. b DSGVO.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Empf\u00e4nger:<\/h3>\n\n\n\n<p>Empf\u00e4nger der Daten sind ggf. Auftragsverarbeiter.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Speicherdauer:<\/h3>\n\n\n\n<p>Wir speichern diese Daten in unseren Systemen bis die gesetzlichen Aufbewahrungsfristen abgelaufen sind. Diese betragen grunds\u00e4tzlich 6 oder 10 Jahre aus Gr\u00fcnden der ordnungsm\u00e4\u00dfigen Buchf\u00fchrung und steuerrechtlichen Anforderungen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Bereitstellung vorgeschrieben oder erforderlich:<\/h3>\n\n\n\n<p>Die Bereitstellung Ihrer personenbezogenen Daten erfolgt freiwillig. Ohne die Bereitstellung Ihrer personenbezogenen Daten k\u00f6nnen wir Ihnen keinen Zugang auf unsere angebotenen Inhalte und Leistungen gew\u00e4hren.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Verwendung von Google Maps<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Art und Zweck der Verarbeitung:<\/h3>\n\n\n\n<p>Auf dieser Webseite nutzen wir das Angebot von Google Maps. Google Maps wird von Google LLC, 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA (nachfolgend \u201eGoogle\u201c) betrieben. Dadurch k\u00f6nnen wir Ihnen interaktive Karten direkt in der Webseite anzeigen und erm\u00f6glichen Ihnen die komfortable Nutzung der Karten-Funktion.<\/p>\n\n\n\n<p>N\u00e4here Informationen \u00fcber die Datenverarbeitung durch Google k\u00f6nnen Sie&nbsp;<a href=\"http:\/\/www.google.com\/privacypolicy.html\">den Google-Datenschutzhinweisen<\/a>&nbsp;entnehmen. Dort k\u00f6nnen Sie im Datenschutzcenter auch Ihre pers\u00f6nlichen Datenschutz-Einstellungen ver\u00e4ndern.<\/p>\n\n\n\n<p>Ausf\u00fchrliche Anleitungen zur Verwaltung der eigenen Daten im Zusammenhang mit Google-Produkten<a href=\"http:\/\/www.dataliberation.org\/\">&nbsp;finden Sie hier<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Rechtsgrundlage:<\/h3>\n\n\n\n<p>Rechtsgrundlage f\u00fcr die Einbindung von Google Maps und dem damit verbundenen Datentransfer zu Google ist Ihre Einwilligung (Art. 6 Abs. 1 lit. a DSGVO).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Empf\u00e4nger:<\/h3>\n\n\n\n<p>Durch den Besuch der Webseite erh\u00e4lt Google Informationen, dass Sie die entsprechende Unterseite unserer Webseite aufgerufen haben. Dies erfolgt unabh\u00e4ngig davon, ob Google ein Nutzerkonto bereitstellt, \u00fcber das Sie eingeloggt sind, oder ob keine Nutzerkonto besteht. Wenn Sie bei Google eingeloggt sind, werden Ihre Daten direkt Ihrem Konto zugeordnet.<\/p>\n\n\n\n<p>Wenn Sie die Zuordnung in Ihrem Profil bei Google nicht w\u00fcnschen, m\u00fcssen Sie sich vor Aktivierung des Buttons bei Google ausloggen. Google speichert Ihre Daten als Nutzungsprofile und nutzt sie f\u00fcr Zwecke der Werbung, Marktforschung und\/oder bedarfsgerechter Gestaltung seiner Webseite. Eine solche Auswertung erfolgt insbesondere (selbst f\u00fcr nicht eingeloggte Nutzer) zur Erbringung bedarfsgerechter Werbung und um andere Nutzer des sozialen Netzwerks \u00fcber Ihre Aktivit\u00e4ten auf unserer Webseite zu informieren. Ihnen steht ein Widerspruchsrecht zu gegen die Bildung dieser Nutzerprofile, wobei Sie sich zur Aus\u00fcbung dessen an Google richten m\u00fcssen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Speicherdauer:<\/h3>\n\n\n\n<p>Wir erheben keine personenbezogenen Daten, durch die Einbindung von Google Maps.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Drittlandtransfer:<\/h3>\n\n\n\n<p>Google verarbeitet Ihre Daten in den USA und hat sich dem EU_US Privacy Shield unterworfen&nbsp;<a href=\"https:\/\/www.privacyshield.gov\/EU-US-Framework\">https:\/\/www.privacyshield.gov\/EU-US-Framework<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Widerruf der Einwilligung:<\/h3>\n\n\n\n<p>Wenn Sie nicht m\u00f6chten, dass Google \u00fcber unseren Internetauftritt Daten \u00fcber Sie erhebt, verarbeitet oder nutzt, k\u00f6nnen Sie in Ihrem Browsereinstellungen JavaScript deaktivieren. In diesem Fall k\u00f6nnen Sie unsere Webseite jedoch nicht oder nur eingeschr\u00e4nkt nutzen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Bereitstellung vorgeschrieben oder erforderlich:<\/h3>\n\n\n\n<p>Die Bereitstellung Ihrer personenbezogenen Daten erfolgt freiwillig, allein auf Basis Ihrer Einwilligung. Sofern Sie den Zugriff unterbinden, kann es hierdurch zu Funktionseinschr\u00e4nkungen auf der Website kommen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cookies<\/h2>\n\n\n\n<p>Unsere Internetseiten verwenden so genannte \u201eCookies\u201c. Cookies sind kleine Textdateien und richten auf Ihrem Endger\u00e4t keinen Schaden an. Sie werden entweder vor\u00fcbergehend f\u00fcr die Dauer einer Sitzung (Session-Cookies) oder dauerhaft (permanente Cookies) auf Ihrem Endger\u00e4t gespeichert. Session-Cookies werden nach Ende Ihres Besuchs automatisch gel\u00f6scht. Permanente Cookies bleiben auf Ihrem Endger\u00e4t gespeichert, bis Sie diese selbst l\u00f6schen&nbsp;oder eine automatische L\u00f6schung durch Ihren Webbrowser erfolgt.<\/p>\n\n\n\n<p>Teilweise k\u00f6nnen auch Cookies von Drittunternehmen auf Ihrem Endger\u00e4t gespeichert werden, wenn Sie unsere Seite betreten (Third-Party-Cookies). Diese erm\u00f6glichen uns oder Ihnen die Nutzung bestimmter Dienstleistungen des Drittunternehmens (z.B. Cookies zur Abwicklung von Zahlungsdienstleistungen).<\/p>\n\n\n\n<p>Cookies haben verschiedene Funktionen. Zahlreiche Cookies sind technisch notwendig, da bestimmte Webseitenfunktionen ohne diese nicht funktionieren w\u00fcrden (z.B. die Warenkorbfunktion oder die Anzeige von Videos). Andere Cookies dienen dazu, das Nutzerverhalten auszuwerten&nbsp;oder Werbung anzuzeigen.<\/p>\n\n\n\n<p>Cookies, die zur Durchf\u00fchrung des elektronischen Kommunikationsvorgangs (notwendige Cookies) oder zur Bereitstellung bestimmter, von Ihnen erw\u00fcnschter Funktionen (funktionale Cookies, z. B. f\u00fcr die Warenkorbfunktion) oder zur Optimierung der Webseite (z.B. Cookies zur Messung des Webpublikums) erforderlich sind, werden auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO gespeichert, sofern keine andere Rechtsgrundlage angegeben wird. Der Websitebetreiber hat ein berechtigtes Interesse an der Speicherung von Cookies zur technisch fehlerfreien und optimierten Bereitstellung seiner Dienste. Sofern eine Einwilligung zur Speicherung von Cookies abgefragt wurde, erfolgt die Speicherung der betreffenden Cookies ausschlie\u00dflich auf Grundlage dieser Einwilligung (Art. 6 Abs. 1 lit. a DSGVO); die Einwilligung ist jederzeit widerrufbar.<\/p>\n\n\n\n<p>Sie k\u00f6nnen Ihren Browser so einstellen, dass Sie \u00fcber das Setzen von Cookies informiert werden und Cookies nur im Einzelfall erlauben, die Annahme von Cookies f\u00fcr bestimmte F\u00e4lle oder generell ausschlie\u00dfen sowie das automatische L\u00f6schen der Cookies beim Schlie\u00dfen des Browsers aktivieren. Bei der Deaktivierung von Cookies kann die Funktionalit\u00e4t dieser Website eingeschr\u00e4nkt sein.<\/p>\n\n\n\n<p>Soweit Cookies von Drittunternehmen oder zu Analysezwecken eingesetzt werden, werden wir Sie hier\u00fcber im Rahmen dieser Datenschutzerkl\u00e4rung gesondert informieren und ggf. eine Einwilligung abfragen. Dies erfolgt \u00fcber ein sogenanntes Cookie-Banner beim ersten Aufruf unserer Seite. Details zu allen von uns gesetzten Cookies entnehmen sie unserer&nbsp;<a href=\"https:\/\/3ddungeon.de\/infos\/cookie-richtlinie-eu\">Cookierichtlinie (EU)<\/a>. Hier haben sie auch die M\u00f6glichkeit ihre Entscheidung zu \u00e4ndern oder zu widerrufen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Server-Log-Dateien<\/h2>\n\n\n\n<p>Der Provider der Seiten erhebt und speichert automatisch Informationen in so genannten Server-Log-Dateien, die Ihr Browser automatisch an uns \u00fcbermittelt. Dies sind:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Browsertyp und Browserversion<\/li>\n\n\n\n<li>verwendetes Betriebssystem<\/li>\n\n\n\n<li>Referrer URL<\/li>\n\n\n\n<li>Hostname des zugreifenden Rechners<\/li>\n\n\n\n<li>Uhrzeit der Serveranfrage<\/li>\n\n\n\n<li>IP-Adresse<\/li>\n<\/ul>\n\n\n\n<p>Eine Zusammenf\u00fchrung dieser Daten mit anderen Datenquellen wird nicht vorgenommen.<\/p>\n\n\n\n<p>Die Erfassung dieser Daten erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Der Websitebetreiber hat ein berechtigtes Interesse an der technisch fehlerfreien Darstellung und der Optimierung seiner Website \u2013 hierzu m\u00fcssen die Server-Log-Files erfasst werden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Kontaktformular<\/h2>\n\n\n\n<p>Wenn Sie uns per Kontaktformular Anfragen zukommen lassen, werden Ihre Angaben aus dem Anfrageformular inklusive der von Ihnen dort angegebenen Kontaktdaten zwecks Bearbeitung der Anfrage und f\u00fcr den Fall von Anschlussfragen bei uns gespeichert. Diese Daten geben wir nicht ohne Ihre Einwilligung weiter.<\/p>\n\n\n\n<p>Die Verarbeitung dieser Daten erfolgt auf Grundlage von Art. 6 Abs. 1 lit. b DSGVO, sofern Ihre Anfrage mit der Erf\u00fcllung eines Vertrags zusammenh\u00e4ngt oder zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich ist. In allen \u00fcbrigen F\u00e4llen beruht die Verarbeitung auf unserem berechtigten Interesse an der effektiven Bearbeitung der an uns gerichteten Anfragen (Art. 6 Abs. 1 lit. f DSGVO) oder auf Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO) sofern diese abgefragt wurde.<\/p>\n\n\n\n<p>Die von Ihnen im Kontaktformular eingegebenen Daten verbleiben bei uns, bis Sie uns zur L\u00f6schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt (z.&nbsp;B. nach abgeschlossener Bearbeitung Ihrer Anfrage). Zwingende gesetzliche Bestimmungen \u2013 insbesondere Aufbewahrungsfristen \u2013 bleiben unber\u00fchrt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Anfrage per E-Mail, Telefon oder Telefax<\/h2>\n\n\n\n<p>Wenn Sie uns per E-Mail, Telefon oder Telefax kontaktieren, wird Ihre Anfrage inklusive aller daraus hervorgehenden personenbezogenen Daten (Name, Anfrage) zum Zwecke der Bearbeitung Ihres Anliegens bei uns gespeichert und verarbeitet. Diese Daten geben wir nicht ohne Ihre Einwilligung weiter.<\/p>\n\n\n\n<p>Die Verarbeitung dieser Daten erfolgt auf Grundlage von Art. 6 Abs. 1 lit. b DSGVO, sofern Ihre Anfrage mit der Erf\u00fcllung eines Vertrags zusammenh\u00e4ngt oder zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich ist. In allen \u00fcbrigen F\u00e4llen beruht die Verarbeitung auf unserem berechtigten Interesse an der effektiven Bearbeitung der an uns gerichteten Anfragen (Art. 6 Abs. 1 lit. f DSGVO) oder auf Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO) sofern diese abgefragt wurde.<\/p>\n\n\n\n<p>Die von Ihnen an uns per Kontaktanfragen \u00fcbersandten Daten verbleiben bei uns, bis Sie uns zur L\u00f6schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt (z.&nbsp;B. nach abgeschlossener Bearbeitung Ihres Anliegens). Zwingende gesetzliche Bestimmungen \u2013 insbesondere gesetzliche Aufbewahrungsfristen \u2013 bleiben unber\u00fchrt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Kommentarfunktion auf dieser Website<\/h2>\n\n\n\n<p>F\u00fcr die Kommentarfunktion auf dieser Seite werden neben Ihrem Kommentar auch Angaben zum Zeitpunkt der Erstellung des Kommentars, Ihre E-Mail-Adresse und, wenn Sie nicht anonym posten, der von Ihnen gew\u00e4hlte Nutzername gespeichert.<\/p>\n\n\n\n<p><strong>Speicherung der IP-Adresse<\/strong><\/p>\n\n\n\n<p>Unsere Kommentarfunktion speichert die IP-Adressen der Nutzer, die Kommentare verfassen. Da wir Kommentare auf dieser Website nicht vor der Freischaltung pr\u00fcfen, ben\u00f6tigen wir diese Daten, um im Falle von Rechtsverletzungen wie Beleidigungen oder Propaganda gegen den Verfasser vorgehen zu k\u00f6nnen.<\/p>\n\n\n\n<p><strong>Abonnieren von Kommentaren<\/strong><\/p>\n\n\n\n<p>Als Nutzer der Seite k\u00f6nnen Sie nach einer Anmeldung Kommentare abonnieren. Sie erhalten eine Best\u00e4tigungsemail, um zu pr\u00fcfen, ob Sie der Inhaber der angegebenen E-Mail-Adresse sind. Sie k\u00f6nnen diese Funktion jederzeit \u00fcber einen Link in den Info-Mails abbestellen. Die im Rahmen des Abonnierens von Kommentaren eingegebenen Daten werden in diesem Fall gel\u00f6scht; wenn Sie diese Daten f\u00fcr andere Zwecke und an anderer Stelle (z.&nbsp;B. Newsletterbestellung) an uns \u00fcbermittelt haben, verbleiben diese Daten jedoch bei uns.<\/p>\n\n\n\n<p><strong>Speicherdauer der Kommentare<\/strong><\/p>\n\n\n\n<p>Die Kommentare und die damit verbundenen Daten (z.&nbsp;B. IP-Adresse) werden gespeichert und verbleiben auf dieser Website, bis der kommentierte Inhalt vollst\u00e4ndig gel\u00f6scht wurde oder die Kommentare aus rechtlichen Gr\u00fcnden gel\u00f6scht werden m\u00fcssen (z.&nbsp;B. beleidigende Kommentare).<\/p>\n\n\n\n<p><strong>Rechtsgrundlage<\/strong><\/p>\n\n\n\n<p>Die Speicherung der Kommentare erfolgt auf Grundlage Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO). Sie k\u00f6nnen eine von Ihnen erteilte Einwilligung jederzeit widerrufen. Dazu reicht eine formlose Mitteilung per E-Mail an uns. Die Rechtm\u00e4\u00dfigkeit der bereits erfolgten Datenverarbeitungsvorg\u00e4nge bleibt vom Widerruf unber\u00fchrt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Google Analytics<\/h2>\n\n\n\n<p>Soweit Sie Ihre Einwilligung erkl\u00e4rt haben, wird auf dieser Website Google Analytics eingesetzt, ein Webanalysedienst der Google Ireland Limited (\u201eGoogle\u201c). Die Nutzung umfasst die Betriebsart \u201eUniversal Analytics\u201c. Hierdurch ist es m\u00f6glich, Daten, Sitzungen und Interaktionen \u00fcber mehrere Ger\u00e4te hinweg einer pseudonymen User-ID zuzuordnen und so die Aktivit\u00e4ten eines Nutzers ger\u00e4te\u00fcbergreifend zu analysieren.<\/p>\n\n\n\n<p>Google Analytics verwendet sog. \u201eCookies\u201c, Textdateien, die auf Ihrem Computer gespeichert werden und die eine Analyse der Benutzung der Website durch Sie erm\u00f6glichen. Die durch das Cookie erzeugten Informationen \u00fcber Ihre Benutzung dieser Website werden in der Regel an einen Server von Google in den USA \u00fcbertragen und dort gespeichert. Im Falle der Aktivierung der IP-Anonymisierung auf dieser Website, wird Ihre IP-Adresse von Google jedoch innerhalb von Mitgliedstaaten der Europ\u00e4ischen Union oder in anderen Vertragsstaaten des Abkommens \u00fcber den Europ\u00e4ischen Wirtschaftsraum zuvor gek\u00fcrzt. Wir weisen Sie darauf hin, dass auf dieser Webseite Google Analytics um eine IP-Anonymisierung erweitert wurde, um eine anonymisierte Erfassung von IP-Adressen (sog. IP-Masking) zu gew\u00e4hrleisten. Die im Rahmen von Google Analytics von Ihrem Browser \u00fcbermittelte IP-Adresse wird nicht mit anderen Daten von Google zusammengef\u00fchrt. N\u00e4here Informationen zu Nutzungsbedingungen und Datenschutz finden Sie unter&nbsp;<a href=\"https:\/\/www.google.com\/analytics\/terms\/de.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.google.com\/analytics\/terms\/de.html<\/a>&nbsp;bzw. unter&nbsp;<a href=\"https:\/\/policies.google.com\/?hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/policies.google.com\/?hl=de<\/a>.<\/p>\n\n\n\n<p><strong>Zwecke der Verarbeitung<\/strong><br>Im Auftrag des Betreibers dieser Website wird Google diese Informationen benutzen, um Ihre Nutzung der Website auszuwerten, um Reports \u00fcber die Websiteaktivit\u00e4ten zusammenzustellen und um weitere mit der Websitenutzung und der Internetnutzung verbundene Dienstleistungen gegen\u00fcber dem Websitebetreiber zu erbringen.<\/p>\n\n\n\n<p><strong>Rechtsgrundlage<\/strong><br>Die Rechtsgrundlage f\u00fcr den Einsatz von Google Analytics ist Ihre Einwilligung gem\u00e4\u00df&nbsp;<a href=\"https:\/\/dsgvo-gesetz.de\/art-6-dsgvo\/\" target=\"_blank\" rel=\"noreferrer noopener\">Art. 6 Abs. 1 S.1 lit. a DSGVO<\/a>.<\/p>\n\n\n\n<p><strong>Empf\u00e4nger \/ Kategorien von Empf\u00e4ngern<\/strong><br>Der Empf\u00e4nger der erhobenen Daten ist Google.<\/p>\n\n\n\n<p><strong>\u00dcbermittlung in Drittstaaten<\/strong><br>Die personenbezogenen Daten werden unter dem EU-US Privacy Shield auf Grundlage des Angemessenheitsbeschlusses der Europ\u00e4ischen Kommission in die USA \u00fcbermittelt. Das Zertifikat k\u00f6nnen Sie&nbsp;<a href=\"https:\/\/www.privacyshield.gov\/participant?id=a2zt000000001L5AAI\" target=\"_blank\" rel=\"noreferrer noopener\">hier<\/a>&nbsp;abrufen.<\/p>\n\n\n\n<p><strong>Dauer der Datenspeicherung<\/strong><br>Die von uns gesendeten und mit Cookies, Nutzerkennungen (z. B. User-ID) oder Werbe-IDs verkn\u00fcpften Daten werden nach 14 Monaten automatisch gel\u00f6scht. Die L\u00f6schung von Daten, deren Aufbewahrungsdauer erreicht ist, erfolgt automatisch einmal im Monat.<\/p>\n\n\n\n<p><strong>Betroffenenrechte<\/strong><br>Sie k\u00f6nnen Ihre Einwilligung jederzeit mit Wirkung f\u00fcr die Zukunft widerrufen, indem Sie die Speicherung der Cookies durch eine entsprechende Einstellung Ihrer Browser-Software verhindern; wir weisen Sie jedoch darauf hin, dass Sie in diesem Fall gegebenenfalls nicht s\u00e4mtliche Funktionen dieser Website vollumf\u00e4nglich werden nutzen k\u00f6nnen.<\/p>\n\n\n\n<p>Sie k\u00f6nnen dar\u00fcber hinaus die Erfassung der durch das Cookie erzeugten und auf Ihre Nutzung der Website bezogenen Daten (inkl. Ihrer IP-Adresse) an Google sowie die Verarbeitung dieser Daten durch Google verhindern, indem Sie das&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\">Browser-Add-on<\/a>&nbsp;herunterladen und installieren. Opt-Out-Cookies verhindern die zuk\u00fcnftige Erfassung Ihrer Daten beim Besuch dieser Website. Um die Erfassung durch Universal Analytics \u00fcber verschiedene Ger\u00e4te hinweg zu verhindern, m\u00fcssen Sie das Opt-Out auf allen genutzten Systemen durchf\u00fchren.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">5. Soziale Medien<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Art und Zweck der Verarbeitung:<\/h3>\n\n\n\n<p>Wir bieten Ihnen auf unserer Webseite die M\u00f6glichkeit der Nutzung von sog. \u201eSocial-Media-Buttons\u201c an. Zum Schutze Ihrer Daten setzen wir bei der Implementierung auf die L\u00f6sung \u201eShariff\u201c. Hierdurch werden diese Buttons auf der Webseite lediglich als Grafik eingebunden, die eine Verlinkung auf die entsprechende Webseite des Button-Anbieters enth\u00e4lt. Durch Anklicken der Grafik werden Sie somit zu den Diensten der jeweiligen Anbieter weitergeleitet. Erst dann werden Ihre Daten an die jeweiligen Anbieter gesendet. Sofern Sie die Grafik nicht anklicken, findet keinerlei Austausch zwischen Ihnen und den Anbietern der Social-Media-Buttons statt. Informationen \u00fcber die Erhebung und Verwendung Ihrer Daten in den sozialen Netzwerken finden Sie in den jeweiligen Nutzungsbedingungen der entsprechenden Anbieter. Mehr Informationen zur Shariff-L\u00f6sung finden Sie hier:&nbsp;<a href=\"http:\/\/www.heise.de\/ct\/artikel\/Shariff-Social-Media-Buttons-mit-Datenschutz-2467514.html\">http:\/\/www.heise.de\/ct\/artikel\/Shariff-Social-Media-Buttons-mit-Datenschutz-2467514.html<\/a><\/p>\n\n\n\n<p>Wir haben auf unserer Website die Social-Media-Buttons folgender Unternehmen eingebunden:<\/p>\n\n\n\n<p>Facebook, WhatsApp &amp; Twitter<\/p>\n\n\n\n<p>Die Verwendung des Shariff Plugins erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Der Websitebetreiber hat ein berechtigtes Interesse an einer m\u00f6glichst umfangreichen Sichtbarkeit in den Sozialen Medien. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO; die Einwilligung ist jederzeit widerrufbar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">6. Newsletter<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Newsletterdaten<\/h3>\n\n\n\n<p>Wenn Sie den auf der Website angebotenen Newsletter beziehen m\u00f6chten, ben\u00f6tigen wir von Ihnen eine E-Mail-Adresse sowie Informationen, welche uns die \u00dcberpr\u00fcfung gestatten, dass Sie der Inhaber der angegebenen E-Mail-Adresse sind und mit dem Empfang des Newsletters einverstanden sind. Weitere Daten werden nicht bzw. nur auf freiwilliger Basis erhoben. Diese Daten verwenden wir ausschlie\u00dflich f\u00fcr den Versand der angeforderten Informationen und geben diese nicht an Dritte weiter.<\/p>\n\n\n\n<p>Die Verarbeitung der in das Newsletteranmeldeformular eingegebenen Daten erfolgt ausschlie\u00dflich auf Grundlage Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO). Die erteilte Einwilligung zur Speicherung der Daten, der E-Mail-Adresse sowie deren Nutzung zum Versand des Newsletters k\u00f6nnen Sie jederzeit widerrufen, etwa \u00fcber den \u201eAustragen\u201c-Link im Newsletter. Die Rechtm\u00e4\u00dfigkeit der bereits erfolgten Datenverarbeitungsvorg\u00e4nge bleibt vom Widerruf unber\u00fchrt.<\/p>\n\n\n\n<p>Die von Ihnen zum Zwecke des Newsletter-Bezugs bei uns hinterlegten Daten werden von uns bis zu Ihrer Austragung aus dem Newsletter bei uns bzw. dem Newsletterdiensteanbieter gespeichert und nach der Abbestellung des Newsletters aus der Newsletterverteilerliste gel\u00f6scht. Daten, die zu anderen Zwecken bei uns gespeichert wurden bleiben hiervon unber\u00fchrt.<\/p>\n\n\n\n<p>Nach Ihrer Austragung aus der Newsletterverteilerliste wird Ihre E-Mail-Adresse bei uns bzw. dem Newsletterdiensteanbieter ggf. in einer Blacklist gespeichert, um k\u00fcnftige Mailings zu verhindern. Die Daten aus der Blacklist werden nur f\u00fcr diesen Zweck verwendet und nicht mit anderen Daten zusammengef\u00fchrt. Dies dient sowohl Ihrem Interesse als auch unserem Interesse an der Einhaltung der gesetzlichen Vorgaben beim Versand von Newslettern (berechtigtes Interesse im Sinne des Art. 6 Abs. 1 lit. f DSGVO). Die Speicherung in der Blacklist ist zeitlich nicht befristet.&nbsp;<strong>Sie k\u00f6nnen der Speicherung widersprechen, sofern Ihre Interessen unser berechtigtes Interesse \u00fcberwiegen.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">7. Plugins und Tools<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">YouTube<\/h3>\n\n\n\n<p>Diese Website bindet Videos der Website YouTube ein. Betreiber der Website ist die Google Ireland Limited (\u201eGoogle\u201c), Gordon House, Barrow Street, Dublin 4, Irland.<\/p>\n\n\n\n<p>Wenn Sie eine unserer Webseiten besuchen, auf denen YouTube eingebunden ist, wird eine Verbindung zu den Servern von YouTube hergestellt. Dabei wird dem YouTube-Server mitgeteilt, welche unserer Seiten Sie besucht haben.<\/p>\n\n\n\n<p>Des Weiteren kann YouTube verschiedene Cookies auf Ihrem Endger\u00e4t speichern. Mit Hilfe dieser Cookies kann YouTube Informationen \u00fcber Besucher dieser Website erhalten. Diese Informationen werden u. a. verwendet, um Videostatistiken zu erfassen, die Anwenderfreundlichkeit zu verbessern und Betrugsversuchen vorzubeugen. Die Cookies verbleiben auf Ihrem Endger\u00e4t, bis Sie sie l\u00f6schen.<\/p>\n\n\n\n<p>Wenn Sie in Ihrem YouTube-Account eingeloggt sind, erm\u00f6glichen Sie YouTube, Ihr Surfverhalten direkt Ihrem pers\u00f6nlichen Profil zuzuordnen. Dies k\u00f6nnen Sie verhindern, indem Sie sich aus Ihrem YouTube-Account ausloggen.<\/p>\n\n\n\n<p>Die Nutzung von YouTube erfolgt im Interesse einer ansprechenden Darstellung unserer Online-Angebote. Dies stellt ein berechtigtes Interesse im Sinne von Art. 6 Abs. 1 lit. f DSGVO dar. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO; die Einwilligung ist jederzeit widerrufbar.<\/p>\n\n\n\n<p>Weitere Informationen zum Umgang mit Nutzerdaten finden Sie in der Datenschutzerkl\u00e4rung von YouTube unter:&nbsp;<a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Google Web Fonts<\/h3>\n\n\n\n<p>Diese Seite nutzt zur einheitlichen Darstellung von Schriftarten so genannte Web Fonts, die von Google bereitgestellt werden. Beim Aufruf einer Seite l\u00e4dt Ihr Browser die ben\u00f6tigten Web Fonts in ihren Browsercache, um Texte und Schriftarten korrekt anzuzeigen.<\/p>\n\n\n\n<p>Zu diesem Zweck muss der von Ihnen verwendete Browser Verbindung zu den Servern von Google aufnehmen. Hierdurch erlangt Google Kenntnis dar\u00fcber, dass \u00fcber Ihre IP-Adresse diese Website aufgerufen wurde. Die Nutzung von Google WebFonts erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Der Webseitenbetreiber hat ein berechtigtes Interesse an der einheitlichen Darstellung des Schriftbildes auf seiner Webseite. Sofern eine entsprechende Einwilligung abgefragt wurde (z. B. eine Einwilligung zur Speicherung von Cookies), erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO; die Einwilligung ist jederzeit widerrufbar.<\/p>\n\n\n\n<p>Wenn Ihr Browser Web Fonts nicht unterst\u00fctzt, wird eine Standardschrift von Ihrem Computer genutzt.<\/p>\n\n\n\n<p>Weitere Informationen zu Google Web Fonts finden Sie unter&nbsp;<a href=\"https:\/\/developers.google.com\/fonts\/faq\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/developers.google.com\/fonts\/faq<\/a>&nbsp;und in der Datenschutzerkl\u00e4rung von Google:&nbsp;<a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">8. \u00c4nderung unserer Datenschutzbestimmungen<\/h2>\n\n\n\n<p>Wir behalten uns vor, diese Datenschutzerkl\u00e4rung anzupassen, damit sie stets den aktuellen rechtlichen Anforderungen entspricht oder um \u00c4nderungen unserer Leistungen in der Datenschutzerkl\u00e4rung umzusetzen, z.B. bei der Einf\u00fchrung neuer Services. F\u00fcr Ihren erneuten Besuch gilt dann die neue Datenschutzerkl\u00e4rung.<\/p>\n\n\n\n<p>Quelle:&nbsp;<a href=\"https:\/\/www.e-recht24.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">eRecht24<\/a>,&nbsp;<a href=\"https:\/\/www.datenschutzbeauftragter-info.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">datenschutzbeauftragter-info.de<\/a>&nbsp;&amp;&nbsp;<a href=\"https:\/\/www.activemind.de\/datenschutz\/datenschutzbeauftragter\/\" target=\"_blank\" rel=\"noreferrer noopener\">activeMind AG<\/a><\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>AMSRB-NATO Club Valley of Washington, D.C. Datenschutzinformationen 1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie&#8230;<\/p>","protected":false},"author":2,"featured_media":0,"parent":2568,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_kadence_starter_templates_imported_post":true,"_kad_post_transparent":"","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"hide","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","cybocfi_hide_featured_image":"","footnotes":""},"class_list":["post-3432","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Datenschutz - AMSRB-NATO Club<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amsrb-nato.com\/de\/home\/datenschutz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutz - AMSRB-NATO Club\" \/>\n<meta property=\"og:description\" content=\"AMSRB-NATO Club Valley of Washington, D.C. Datenschutzinformationen 1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amsrb-nato.com\/de\/home\/datenschutz\/\" \/>\n<meta property=\"og:site_name\" content=\"AMSRB-NATO Club\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GGW810A\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-01T11:44:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"19\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amsrb-nato.com\\\/home\\\/datenschutz\\\/\",\"url\":\"https:\\\/\\\/amsrb-nato.com\\\/home\\\/datenschutz\\\/\",\"name\":\"Datenschutz - AMSRB-NATO Club\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amsrb-nato.com\\\/#website\"},\"datePublished\":\"2020-12-23T05:54:00+00:00\",\"dateModified\":\"2023-06-01T11:44:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amsrb-nato.com\\\/home\\\/datenschutz\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amsrb-nato.com\\\/home\\\/datenschutz\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amsrb-nato.com\\\/home\\\/datenschutz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/amsrb-nato.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\\\/\\\/amsrb-nato.com\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Datenschutz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amsrb-nato.com\\\/#website\",\"url\":\"https:\\\/\\\/amsrb-nato.com\\\/\",\"name\":\"Emirat Turtles e.V. Ancient Free & Accepted Masons\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amsrb-nato.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amsrb-nato.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amsrb-nato.com\\\/#organization\",\"name\":\"Emirat Turtles e.V. Ancient Free & Accepted Masons\",\"url\":\"https:\\\/\\\/amsrb-nato.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/amsrb-nato.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.3ddungeon.de\\\/810a\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/cropped-810a_Dual_Bijou.gif?fit=640%2C313&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.3ddungeon.de\\\/810a\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/cropped-810a_Dual_Bijou.gif?fit=640%2C313&ssl=1\",\"width\":640,\"height\":313,\"caption\":\"Emirat Turtles e.V. Ancient Free & Accepted Masons\"},\"image\":{\"@id\":\"https:\\\/\\\/amsrb-nato.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GGW810A\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutz - AMSRB-NATO Club","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amsrb-nato.com\/de\/home\/datenschutz\/","og_locale":"de_DE","og_type":"article","og_title":"Datenschutz - AMSRB-NATO Club","og_description":"AMSRB-NATO Club Valley of Washington, D.C. Datenschutzinformationen 1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie...","og_url":"https:\/\/amsrb-nato.com\/de\/home\/datenschutz\/","og_site_name":"AMSRB-NATO Club","article_publisher":"https:\/\/www.facebook.com\/GGW810A","article_modified_time":"2023-06-01T11:44:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"19\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/amsrb-nato.com\/home\/datenschutz\/","url":"https:\/\/amsrb-nato.com\/home\/datenschutz\/","name":"Datenschutz - AMSRB-NATO Club","isPartOf":{"@id":"https:\/\/amsrb-nato.com\/#website"},"datePublished":"2020-12-23T05:54:00+00:00","dateModified":"2023-06-01T11:44:44+00:00","breadcrumb":{"@id":"https:\/\/amsrb-nato.com\/home\/datenschutz\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amsrb-nato.com\/home\/datenschutz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/amsrb-nato.com\/home\/datenschutz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/amsrb-nato.com\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/amsrb-nato.com\/"},{"@type":"ListItem","position":3,"name":"Datenschutz"}]},{"@type":"WebSite","@id":"https:\/\/amsrb-nato.com\/#website","url":"https:\/\/amsrb-nato.com\/","name":"Emirat Turtles e.V. Ancient Free & Accepted Masons","description":"","publisher":{"@id":"https:\/\/amsrb-nato.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amsrb-nato.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/amsrb-nato.com\/#organization","name":"Emirat Turtles e.V. Ancient Free & Accepted Masons","url":"https:\/\/amsrb-nato.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/amsrb-nato.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.3ddungeon.de\/810a\/wp-content\/uploads\/2023\/02\/cropped-810a_Dual_Bijou.gif?fit=640%2C313&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.3ddungeon.de\/810a\/wp-content\/uploads\/2023\/02\/cropped-810a_Dual_Bijou.gif?fit=640%2C313&ssl=1","width":640,"height":313,"caption":"Emirat Turtles e.V. Ancient Free & Accepted Masons"},"image":{"@id":"https:\/\/amsrb-nato.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GGW810A"]}]}},"_links":{"self":[{"href":"https:\/\/amsrb-nato.com\/de\/wp-json\/wp\/v2\/pages\/3432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amsrb-nato.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/amsrb-nato.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/amsrb-nato.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/amsrb-nato.com\/de\/wp-json\/wp\/v2\/comments?post=3432"}],"version-history":[{"count":7,"href":"https:\/\/amsrb-nato.com\/de\/wp-json\/wp\/v2\/pages\/3432\/revisions"}],"predecessor-version":[{"id":5184,"href":"https:\/\/amsrb-nato.com\/de\/wp-json\/wp\/v2\/pages\/3432\/revisions\/5184"}],"up":[{"embeddable":true,"href":"https:\/\/amsrb-nato.com\/de\/wp-json\/wp\/v2\/pages\/2568"}],"wp:attachment":[{"href":"https:\/\/amsrb-nato.com\/de\/wp-json\/wp\/v2\/media?parent=3432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}